{"id":4932,"date":"2026-05-06T11:56:38","date_gmt":"2026-05-06T11:56:38","guid":{"rendered":"https:\/\/cobandalucia.org\/?p=4932"},"modified":"2026-05-06T12:05:31","modified_gmt":"2026-05-06T12:05:31","slug":"programa-de-desarrollo-directivo-mujeres-con-alto-potencial-eoi","status":"publish","type":"post","link":"https:\/\/cobandalucia.org\/en\/programa-de-desarrollo-directivo-mujeres-con-alto-potencial-eoi\/","title":{"rendered":"Programa de Desarrollo Directivo &#8211; Mujeres con Alto Potencial &#8211; EOI"},"content":{"rendered":"<p>Nos complace informarte que tras el acuerdo cerrado con <strong>EOI<\/strong>, dicha entidad celebra el pr\u00f3ximo <strong>28 de mayo<\/strong> la 4\u00aa Edici\u00f3n del <strong>Programa de Desarrollo para la Direcci\u00f3n \u2013 Mujeres con Alto Potencial. <\/strong><\/p>\n<p>Desde EOI, impulsan el talento y el liderazgo femenino desde una visi\u00f3n estrat\u00e9gica de impacto social y empresarial. Es por ello que este programa prepara a la mujer para asumir responsabilidades directivas y fortalecer el perfil profesional a trav\u00e9s del desarrollo de competencias clave, visi\u00f3n estrat\u00e9gica y conexi\u00f3n con una red de mujeres l\u00edderes de distintos sectores.<\/p>\n<p><strong>\u00bfQu\u00e9 ofrece el programa?<\/strong><\/p>\n<ul>\n<li><strong>Liderazgo Humanista:\u00a0<\/strong>Este bloque incluye liderazgo influyente, gesti\u00f3n de equipos de alto rendimiento, negociaci\u00f3n, comunicaci\u00f3n de alto impacto, gesti\u00f3n emocional e inteligencia artificial aplicada a la innovaci\u00f3n.<\/li>\n<li><strong>Visi\u00f3n integral del negocio:<\/strong>\u00a0Finanzas para la toma de decisiones, estrategia, transformaci\u00f3n digital de los negocios, marketing estrat\u00e9gico y gesti\u00f3n de clientes, gesti\u00f3n operativa, gesti\u00f3n del talento y marca personal,\u00a0y claves del entorno econ\u00f3mico actual.<\/li>\n<li>Acompa\u00f1amiento personalizado:\u00a0Proceso de\u00a0<strong>coaching individual<\/strong>\u00a0para potenciar el autoconocimiento y el desarrollo profesional.<\/li>\n<li><strong>Networking\u00a0<\/strong>de alto valor:\u00a0Acceso a la red\u00a0<strong>Ejecutivas EOI<\/strong>, que conecta a mujeres directivas de diversos sectores para generar sinergias y oportunidades<\/li>\n<\/ul>\n<p><strong>Datos clave del programa:<\/strong><\/p>\n<ul>\n<li><strong>Inicio:<\/strong>\u00a028 de mayo<\/li>\n<li><strong>Duraci\u00f3n:<\/strong>\u00a0\u00b14-6 meses; 256 horas\u00a0(84h presenciales, 150h online, 22h coaching)<\/li>\n<li><strong>Sesiones: <\/strong><em>S<\/em>esiones presenciales jueves y viernes, en semanas alternas, repartidas en mayo-junio, septiembre y noviembre + 9 semanas online.<\/li>\n<\/ul>\n<ul>\n<li><strong>Precio especial<\/strong> para colegiadas: 5.160 \u20ac &#8211; (s\u00f3lo debes presentar tu certificado de colegiada baj\u00e1ndotelo desde tu ficha colegial)<\/li>\n<li><strong><a href=\"https:\/\/online.flippingbook.com\/view\/864859457\/\" target=\"_blank\" rel=\"noopener\">Brochure<\/a><\/strong> del programa<\/li>\n<\/ul>\n<p>Si deseas formalizar tu inscripci\u00f3n, puedes hacerlo\u00a0<strong><a href=\"https:\/\/www.eoi.es\/es\/cursos\/89552\/programa-de-desarrollo-para-la-direccion-mujeres-con-alto-potencial-sevilla\/formulario-admision\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>\u00a0,<\/strong>\u00a0adjuntando tu CV o perfil de LinkedIn.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, no dudes en contactarles.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Nos complace informarte que tras el acuerdo cerrado con EOI,  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":4933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":""},"categories":[69,67],"tags":[],"class_list":["post-4932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion","category-general"],"_links":{"self":[{"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/posts\/4932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/comments?post=4932"}],"version-history":[{"count":7,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/posts\/4932\/revisions"}],"predecessor-version":[{"id":4940,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/posts\/4932\/revisions\/4940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/media\/4933"}],"wp:attachment":[{"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/media?parent=4932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/categories?post=4932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cobandalucia.org\/en\/wp-json\/wp\/v2\/tags?post=4932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}